{"id":2609,"date":"2025-10-28T08:38:18","date_gmt":"2025-10-28T07:38:18","guid":{"rendered":"https:\/\/politicasocial.vinaros.es\/hablemos-de-salud-mental\/"},"modified":"2026-07-09T10:28:57","modified_gmt":"2026-07-09T08:28:57","slug":"hablemos-de-salud-mental","status":"publish","type":"post","link":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/","title":{"rendered":"Hablemos de Salud Mental"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El dimarts dia 28 d&#8217;octubre a les 20h a la Casa Membrillera es presentar\u00e0 el v\u00eddeo \u00abParlem de Salut Mental\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">El martes 28 de octubre, a las 20:00 h, en la Casa Membrillera, se presentar\u00e1 el v\u00eddeo \u201cHablemos de Salud Mental\u201d. <\/p>\n\n<p class=\"wp-block-paragraph\">La presentaci\u00f3n del v\u00eddeo se llevar\u00e1 a cabo con un coloquio en el que se debatir\u00e1 sobre las mismas preguntas y con las respuestas de personas vinculadas al CRIS y profesionales de la comunicaci\u00f3n, Julio Vidal y Cl\u00e0udia C\u00f3zar. <\/p>\n\n<p class=\"wp-block-paragraph\">El aforo del espacio es limitado. Os esperamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dimarts dia 28 d&#8217;octubre a les 20h a la Casa Membrillera es presentar\u00e0 el v\u00eddeo \u00abParlem de Salut Mental\u00bb. El martes 28 de octubre, a las 20:00 h, en la Casa Membrillera, se presentar\u00e1 el v\u00eddeo \u201cHablemos de Salud Mental\u201d. La presentaci\u00f3n del v\u00eddeo se llevar\u00e1 a cabo con un coloquio en el que [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicios-sociales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hablemos de Salud Mental - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hablemos de Salud Mental - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\" \/>\n<meta property=\"og:description\" content=\"El dimarts dia 28 d&#8217;octubre a les 20h a la Casa Membrillera es presentar\u00e0 el v\u00eddeo \u00abParlem de Salut Mental\u00bb. El martes 28 de octubre, a las 20:00 h, en la Casa Membrillera, se presentar\u00e1 el v\u00eddeo \u201cHablemos de Salud Mental\u201d. La presentaci\u00f3n del v\u00eddeo se llevar\u00e1 a cabo con un coloquio en el que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-28T07:38:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T08:28:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"884\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emiliano Pradas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emiliano Pradas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/\"},\"author\":{\"name\":\"Emiliano Pradas\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#\\\/schema\\\/person\\\/0f258553398adb489b518c6140061b26\"},\"headline\":\"Hablemos de Salud Mental\",\"datePublished\":\"2025-10-28T07:38:18+00:00\",\"dateModified\":\"2026-07-09T08:28:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/\"},\"wordCount\":97,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg\",\"articleSection\":[\"Servicios Sociales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/\",\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/\",\"name\":\"Hablemos de Salud Mental - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg\",\"datePublished\":\"2025-10-28T07:38:18+00:00\",\"dateModified\":\"2026-07-09T08:28:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#\\\/schema\\\/person\\\/0f258553398adb489b518c6140061b26\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg\",\"contentUrl\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg\",\"width\":884,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/hablemos-de-salud-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios Sociales\",\"item\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/categoria\\\/servicios-sociales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hablemos de Salud Mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/\",\"name\":\"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\",\"description\":\"Regidoria de Pol\u00edtica Social\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#\\\/schema\\\/person\\\/0f258553398adb489b518c6140061b26\",\"name\":\"Emiliano Pradas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/309e29c7e06df00f774eb756d7739d303be192fe789cd8e357e415d8f9339126?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/309e29c7e06df00f774eb756d7739d303be192fe789cd8e357e415d8f9339126?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/309e29c7e06df00f774eb756d7739d303be192fe789cd8e357e415d8f9339126?s=96&d=mm&r=g\",\"caption\":\"Emiliano Pradas\"},\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hablemos de Salud Mental - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/","og_locale":"es_ES","og_type":"article","og_title":"Hablemos de Salud Mental - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","og_description":"El dimarts dia 28 d&#8217;octubre a les 20h a la Casa Membrillera es presentar\u00e0 el v\u00eddeo \u00abParlem de Salut Mental\u00bb. El martes 28 de octubre, a las 20:00 h, en la Casa Membrillera, se presentar\u00e1 el v\u00eddeo \u201cHablemos de Salud Mental\u201d. La presentaci\u00f3n del v\u00eddeo se llevar\u00e1 a cabo con un coloquio en el que [&hellip;]","og_url":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/","og_site_name":"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","article_published_time":"2025-10-28T07:38:18+00:00","article_modified_time":"2026-07-09T08:28:57+00:00","og_image":[{"width":884,"height":1920,"url":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg","type":"image\/jpeg"}],"author":"Emiliano Pradas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Emiliano Pradas"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#article","isPartOf":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/"},"author":{"name":"Emiliano Pradas","@id":"https:\/\/politicasocial.vinaros.es\/es\/#\/schema\/person\/0f258553398adb489b518c6140061b26"},"headline":"Hablemos de Salud Mental","datePublished":"2025-10-28T07:38:18+00:00","dateModified":"2026-07-09T08:28:57+00:00","mainEntityOfPage":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/"},"wordCount":97,"commentCount":0,"image":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg","articleSection":["Servicios Sociales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/","url":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/","name":"Hablemos de Salud Mental - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","isPartOf":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#primaryimage"},"image":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg","datePublished":"2025-10-28T07:38:18+00:00","dateModified":"2026-07-09T08:28:57+00:00","author":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/#\/schema\/person\/0f258553398adb489b518c6140061b26"},"breadcrumb":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#primaryimage","url":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg","contentUrl":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-27-at-12.33.44.jpeg","width":884,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/politicasocial.vinaros.es\/es\/hablemos-de-salud-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/politicasocial.vinaros.es\/es\/"},{"@type":"ListItem","position":2,"name":"Servicios Sociales","item":"https:\/\/politicasocial.vinaros.es\/es\/categoria\/servicios-sociales\/"},{"@type":"ListItem","position":3,"name":"Hablemos de Salud Mental"}]},{"@type":"WebSite","@id":"https:\/\/politicasocial.vinaros.es\/es\/#website","url":"https:\/\/politicasocial.vinaros.es\/es\/","name":"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","description":"Regidoria de Pol\u00edtica Social","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/politicasocial.vinaros.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/politicasocial.vinaros.es\/es\/#\/schema\/person\/0f258553398adb489b518c6140061b26","name":"Emiliano Pradas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/309e29c7e06df00f774eb756d7739d303be192fe789cd8e357e415d8f9339126?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/309e29c7e06df00f774eb756d7739d303be192fe789cd8e357e415d8f9339126?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/309e29c7e06df00f774eb756d7739d303be192fe789cd8e357e415d8f9339126?s=96&d=mm&r=g","caption":"Emiliano Pradas"},"url":"https:\/\/politicasocial.vinaros.es\/es"}]}},"_links":{"self":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts\/2609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/comments?post=2609"}],"version-history":[{"count":3,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts\/2609\/revisions"}],"predecessor-version":[{"id":2612,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts\/2609\/revisions\/2612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/media\/2405"}],"wp:attachment":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/media?parent=2609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/categories?post=2609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/tags?post=2609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}