{"id":2641,"date":"2024-10-01T11:34:14","date_gmt":"2024-10-01T09:34:14","guid":{"rendered":"https:\/\/politicasocial.vinaros.es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/"},"modified":"2026-07-09T11:16:34","modified_gmt":"2026-07-09T09:16:34","slug":"vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente","status":"publish","type":"post","link":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/","title":{"rendered":"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Vida independiente y asistencia personal para los t\u00e9cnicos de Servicios Sociales del Baix Maestrat y Els Ports.<\/h2>\n\n<p class=\"wp-block-paragraph\">El pasado mi\u00e9rcoles tuvo lugar en Vinar\u00f2s la charla \u201cVida Independiente y Asistencia Personal, el camino hacia la vida independiente\u201d, organizada por la Oficina para la Vida Independiente Sole Arnau Ripoll\u00e8s de Castell\u00f3n, con la colaboraci\u00f3n de los Servicios Sociales del Ayuntamiento de Vinar\u00f2s y del supervisor del \u00e1rea Baix Maestrat\u2013Els Ports, Enrique Ferrer Lorente.<\/p>\n\n<p class=\"wp-block-paragraph\">La jornada formativa para t\u00e9cnicos y profesionales de los Servicios Sociales vers\u00f3 sobre la filosof\u00eda de vida independiente de las personas con diversidad funcional, un movimiento que empodera a las personas con diversidad funcional, ensalzando la autogesti\u00f3n y la toma de decisiones sobre sus vidas, y rechazando tesis m\u00e1s asistencialistas y segregadoras como pueden ser las instituciones residenciales o la escuela de educaci\u00f3n especial.<\/p>\n\n<p class=\"wp-block-paragraph\">A la charla, a la que acudieron representantes de los Servicios Sociales de municipios de toda la comarca, se inform\u00f3 sobre la prestaci\u00f3n del asistente personal, recogida dentro del cat\u00e1logo de la dependencia de la Generalitat Valenciana. Esta prestaci\u00f3n genera niveles de inclusi\u00f3n, participaci\u00f3n en la comunidad y autogesti\u00f3n de las personas con diversidad funcional superiores a otras prestaciones.<\/p>\n\n<p class=\"wp-block-paragraph\">Toda la informaci\u00f3n sobre esta prestaci\u00f3n se puede encontrar en los Servicios Sociales municipales, as\u00ed como en la <a href=\"https:\/\/ovicastello.org\/\">Oficina para la Vida Independiente,<\/a> que prestan asesoramiento y apoyo en todo el proceso de solicitud de la prestaci\u00f3n y de puesta en marcha una vez aprobada.<\/p>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se puede encontrar toda la informaci\u00f3n en la <a href=\"\">Oficina de Vida Independiente<\/a>, espacio web donde se concentra toda la informaci\u00f3n relativa a los servicios y recursos que se prestan desde la OVI para las personas con diversidad funcional, as\u00ed como informaci\u00f3n sobre la vida independiente y la asistencia personal como recurso empoderador de las personas con diversidad funcional.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vida independiente y asistencia personal para los t\u00e9cnicos de Servicios Sociales del Baix Maestrat y Els Ports. El pasado mi\u00e9rcoles tuvo lugar en Vinar\u00f2s la charla \u201cVida Independiente y Asistencia Personal, el camino hacia la vida independiente\u201d, organizada por la Oficina para la Vida Independiente Sole Arnau Ripoll\u00e8s de Castell\u00f3n, con la colaboraci\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicios-sociales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vida Independiente y Asistencia Personal, el camino hacia la vida independiente. - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente. - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\" \/>\n<meta property=\"og:description\" content=\"Vida independiente y asistencia personal para los t\u00e9cnicos de Servicios Sociales del Baix Maestrat y Els Ports. El pasado mi\u00e9rcoles tuvo lugar en Vinar\u00f2s la charla \u201cVida Independiente y Asistencia Personal, el camino hacia la vida independiente\u201d, organizada por la Oficina para la Vida Independiente Sole Arnau Ripoll\u00e8s de Castell\u00f3n, con la colaboraci\u00f3n de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T09:34:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T09:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2024\/10\/photo_2024-09-26_09-28-12-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Pru\u00f1onosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Pru\u00f1onosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/\"},\"author\":{\"name\":\"David Pru\u00f1onosa\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#\\\/schema\\\/person\\\/3b1e431ee719cc0fb03b0f048733b979\"},\"headline\":\"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente.\",\"datePublished\":\"2024-10-01T09:34:14+00:00\",\"dateModified\":\"2026-07-09T09:16:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/\"},\"wordCount\":336,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/photo_2024-09-26_09-28-12-2.jpg\",\"articleSection\":[\"Servicios Sociales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/\",\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/\",\"name\":\"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente. - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/photo_2024-09-26_09-28-12-2.jpg\",\"datePublished\":\"2024-10-01T09:34:14+00:00\",\"dateModified\":\"2026-07-09T09:16:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#\\\/schema\\\/person\\\/3b1e431ee719cc0fb03b0f048733b979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/photo_2024-09-26_09-28-12-2.jpg\",\"contentUrl\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/photo_2024-09-26_09-28-12-2.jpg\",\"width\":960,\"height\":699},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios Sociales\",\"item\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/categoria\\\/servicios-sociales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/\",\"name\":\"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s\",\"description\":\"Regidoria de Pol\u00edtica Social\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\\\/#\\\/schema\\\/person\\\/3b1e431ee719cc0fb03b0f048733b979\",\"name\":\"David Pru\u00f1onosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fc128946e8072351e6094f5d9d8cbf13b1c44e70e2c991bc747c7dc60f0b5a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fc128946e8072351e6094f5d9d8cbf13b1c44e70e2c991bc747c7dc60f0b5a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fc128946e8072351e6094f5d9d8cbf13b1c44e70e2c991bc747c7dc60f0b5a5?s=96&d=mm&r=g\",\"caption\":\"David Pru\u00f1onosa\"},\"url\":\"https:\\\/\\\/politicasocial.vinaros.es\\\/es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente. - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/","og_locale":"es_ES","og_type":"article","og_title":"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente. - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","og_description":"Vida independiente y asistencia personal para los t\u00e9cnicos de Servicios Sociales del Baix Maestrat y Els Ports. El pasado mi\u00e9rcoles tuvo lugar en Vinar\u00f2s la charla \u201cVida Independiente y Asistencia Personal, el camino hacia la vida independiente\u201d, organizada por la Oficina para la Vida Independiente Sole Arnau Ripoll\u00e8s de Castell\u00f3n, con la colaboraci\u00f3n de los [&hellip;]","og_url":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/","og_site_name":"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","article_published_time":"2024-10-01T09:34:14+00:00","article_modified_time":"2026-07-09T09:16:34+00:00","og_image":[{"width":960,"height":699,"url":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2024\/10\/photo_2024-09-26_09-28-12-2.jpg","type":"image\/jpeg"}],"author":"David Pru\u00f1onosa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Pru\u00f1onosa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#article","isPartOf":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/"},"author":{"name":"David Pru\u00f1onosa","@id":"https:\/\/politicasocial.vinaros.es\/es\/#\/schema\/person\/3b1e431ee719cc0fb03b0f048733b979"},"headline":"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente.","datePublished":"2024-10-01T09:34:14+00:00","dateModified":"2026-07-09T09:16:34+00:00","mainEntityOfPage":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/"},"wordCount":336,"commentCount":0,"image":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#primaryimage"},"thumbnailUrl":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2024\/10\/photo_2024-09-26_09-28-12-2.jpg","articleSection":["Servicios Sociales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/","url":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/","name":"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente. - Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","isPartOf":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#primaryimage"},"image":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#primaryimage"},"thumbnailUrl":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2024\/10\/photo_2024-09-26_09-28-12-2.jpg","datePublished":"2024-10-01T09:34:14+00:00","dateModified":"2026-07-09T09:16:34+00:00","author":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/#\/schema\/person\/3b1e431ee719cc0fb03b0f048733b979"},"breadcrumb":{"@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#primaryimage","url":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2024\/10\/photo_2024-09-26_09-28-12-2.jpg","contentUrl":"https:\/\/politicasocial.vinaros.es\/wp-content\/uploads\/2024\/10\/photo_2024-09-26_09-28-12-2.jpg","width":960,"height":699},{"@type":"BreadcrumbList","@id":"https:\/\/politicasocial.vinaros.es\/es\/vida-independiente-y-asistencia-personal-el-camino-hacia-la-vida-independiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/politicasocial.vinaros.es\/es\/"},{"@type":"ListItem","position":2,"name":"Servicios Sociales","item":"https:\/\/politicasocial.vinaros.es\/es\/categoria\/servicios-sociales\/"},{"@type":"ListItem","position":3,"name":"Vida Independiente y Asistencia Personal, el camino hacia la vida independiente."}]},{"@type":"WebSite","@id":"https:\/\/politicasocial.vinaros.es\/es\/#website","url":"https:\/\/politicasocial.vinaros.es\/es\/","name":"Pol\u00edtica Social - Ajuntament de Vinar\u00f2s","description":"Regidoria de Pol\u00edtica Social","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/politicasocial.vinaros.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/politicasocial.vinaros.es\/es\/#\/schema\/person\/3b1e431ee719cc0fb03b0f048733b979","name":"David Pru\u00f1onosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5fc128946e8072351e6094f5d9d8cbf13b1c44e70e2c991bc747c7dc60f0b5a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fc128946e8072351e6094f5d9d8cbf13b1c44e70e2c991bc747c7dc60f0b5a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fc128946e8072351e6094f5d9d8cbf13b1c44e70e2c991bc747c7dc60f0b5a5?s=96&d=mm&r=g","caption":"David Pru\u00f1onosa"},"url":"https:\/\/politicasocial.vinaros.es\/es"}]}},"_links":{"self":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts\/2641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/comments?post=2641"}],"version-history":[{"count":3,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts\/2641\/revisions"}],"predecessor-version":[{"id":2644,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/posts\/2641\/revisions\/2644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/media\/2204"}],"wp:attachment":[{"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/media?parent=2641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/categories?post=2641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicasocial.vinaros.es\/es\/wp-json\/wp\/v2\/tags?post=2641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}